{"id":14960,"date":"2025-01-28T08:46:23","date_gmt":"2025-01-28T07:46:23","guid":{"rendered":"https:\/\/www.danubecommission.org\/dc\/?p=14960"},"modified":"2025-06-16T12:33:14","modified_gmt":"2025-06-16T11:33:14","slug":"102e-session-de-la-commission-du-danube-23-janvier-2025","status":"publish","type":"post","link":"https:\/\/www.danubecommission.org\/dc\/fr\/2025\/01\/28\/102e-session-de-la-commission-du-danube-23-janvier-2025\/","title":{"rendered":"102<sup>e<\/sup> session de la Commission du Danube (23 janvier 2025)"},"content":{"rendered":"<p style=\"text-align: justify;\">Le 23 janvier 2025, la Commission du Danube (CD) a continu\u00e9 les travaux de la 102<sup>e<\/sup> session sous la pr\u00e9sidence du Repr\u00e9sentant de la Bulgarie \u00e0 la Commission du Danube, Son Excellence M. l\u2019Ambassadeur Christo Polendakov, dans le b\u00e2timent de la Commission du Danube \u00e0 Budapest.<\/p>\n<p>Au d\u00e9but de la s\u00e9ance, la d\u00e9l\u00e9gation de l\u2019Ukraine a inform\u00e9 sur les attaques de drones russes contre des cibles civiles et des infrastructures portuaires en Ukraine, dans la matin\u00e9e du 17 janvier, qui ont viol\u00e9 le droit international, ainsi que la navigation libre et en s\u00e9curit\u00e9 sur le Danube.\u00a0 Celle-ci a rappel\u00e9 que la D\u00e9cision de la 12<sup>e<\/sup> session extraordinaire (doc. CD\/SES-XII Extr.\/3) a imput\u00e9 \u00e0 la Russie les dommages \u00e9conomiques d\u00e9j\u00e0 caus\u00e9s et se produisant actuellement suite \u00e0 la r\u00e9duction des activit\u00e9s de transport et de transbordement sur l\u2019ensemble du Danube, li\u00e9e aux dangers de la guerre dans le delta du Danube et la mer Noire.<\/p>\n<p style=\"text-align: justify;\">Au cours de la partie \u00e0 huis clos de la 102<sup>e<\/sup> session, les d\u00e9l\u00e9gations ont abord\u00e9 un certain nombre de questions juridiques \u00e0 leur ordre du jour, dans le cadre du processus de r\u00e9forme de l&#8217;organisation. Les participants ont convenu d&#8217;\u00e9tablir l&#8217;anglais en tant que langue de travail, \u00e0 c\u00f4t\u00e9 de l&#8217;allemand, dans toutes les r\u00e9unions de la Commission du Danube \u00e0 partir du 1<sup>er<\/sup> juillet 2026. Les Etats danubiens ont approuv\u00e9 une nouvelle proc\u00e9dure de s\u00e9lection de leurs conseillers au sein du Secr\u00e9tariat, laquelle pr\u00e9voit un concours ouvert et une proc\u00e9dure concurrentielle afin d&#8217;accro\u00eetre la transparence et l&#8217;efficacit\u00e9 de la Commission.<\/p>\n<p style=\"text-align: justify;\">Les aspects financiers de l&#8217;activit\u00e9 de la Commission du Danube ont \u00e9galement \u00e9t\u00e9 analys\u00e9s. Les d\u00e9l\u00e9gations ont d\u00e9battu et approuv\u00e9 le budget pour 2025, y compris la question de la dette accumul\u00e9e et des p\u00e9nalit\u00e9s de la F\u00e9d\u00e9ration de Russie qui s&#8217;\u00e9l\u00e8vent \u00e0 371.373,27 euros pour la p\u00e9riode 2018-2024.<\/p>\n<p><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-14947 size-full aligncenter\" src=\"https:\/\/www.danubecommission.org\/dc\/wp-content\/uploads\/2025\/01\/102_20250123.jpg\" alt=\"\" width=\"800\" height=\"297\" srcset=\"https:\/\/www.danubecommission.org\/dc\/wp-content\/uploads\/2025\/01\/102_20250123.jpg 800w, https:\/\/www.danubecommission.org\/dc\/wp-content\/uploads\/2025\/01\/102_20250123-300x111.jpg 300w, https:\/\/www.danubecommission.org\/dc\/wp-content\/uploads\/2025\/01\/102_20250123-768x285.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 23 janvier 2025, la Commission du Danube (CD) a continu\u00e9 les travaux de la 102<sup>e<\/sup> session sous la pr\u00e9sidence du Repr\u00e9sentant de la Bulgarie \u00e0 la Commission du Danube, Son Excellence M. l\u2019Ambassadeur Christo Polendakov, dans le b\u00e2timent de la Commission du Danube \u00e0 Budapest.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[365],"tags":[],"class_list":["post-14960","post","type-post","status-publish","format-standard","hentry","category-reunions"],"_links":{"self":[{"href":"https:\/\/www.danubecommission.org\/dc\/wp-json\/wp\/v2\/posts\/14960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.danubecommission.org\/dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.danubecommission.org\/dc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.danubecommission.org\/dc\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.danubecommission.org\/dc\/wp-json\/wp\/v2\/comments?post=14960"}],"version-history":[{"count":2,"href":"https:\/\/www.danubecommission.org\/dc\/wp-json\/wp\/v2\/posts\/14960\/revisions"}],"predecessor-version":[{"id":15409,"href":"https:\/\/www.danubecommission.org\/dc\/wp-json\/wp\/v2\/posts\/14960\/revisions\/15409"}],"wp:attachment":[{"href":"https:\/\/www.danubecommission.org\/dc\/wp-json\/wp\/v2\/media?parent=14960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.danubecommission.org\/dc\/wp-json\/wp\/v2\/categories?post=14960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.danubecommission.org\/dc\/wp-json\/wp\/v2\/tags?post=14960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}