{"id":9475,"date":"2021-10-22T10:22:13","date_gmt":"2021-10-22T09:22:13","guid":{"rendered":"https:\/\/www.danubecommission.org\/dc\/?p=9475"},"modified":"2021-10-22T11:08:27","modified_gmt":"2021-10-22T10:08:27","slug":"reunion-dexperts-pour-le-developpement-des-ports-et-des-operations-portuaires-re-ports","status":"publish","type":"post","link":"https:\/\/www.danubecommission.org\/dc\/fr\/2021\/10\/22\/reunion-dexperts-pour-le-developpement-des-ports-et-des-operations-portuaires-re-ports\/","title":{"rendered":"R\u00e9union d\u2019experts pour le d\u00e9veloppement des ports et des op\u00e9rations portuaires  (RE PORTS)"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Le 30 septembre 2021, la Commission du Danube (CD) a organis\u00e9 une premi\u00e8re r\u00e9union\u00a0 d\u2019experts pour le d\u00e9veloppement des ports et des op\u00e9rations portuaires (RE PORTS). Quelque 80 personnes ont particip\u00e9 aux travaux de cette r\u00e9union en r\u00e9gime en ligne, dont plus de 30 repr\u00e9sentants d\u2019administrations des ports danubiens. A la r\u00e9union, en plus des langues officielles de la CD, les experts ont utilis\u00e9 l\u2019anglais. La r\u00e9union s\u2019est d\u00e9roul\u00e9e sous la pr\u00e9sidence de Monsieur Werner Auer, Directeur g\u00e9n\u00e9ral du port autrichien d\u2019Enns.<\/p>\n<p style=\"text-align: justify;\">Les travaux de la r\u00e9union d\u2019experts ont \u00e9t\u00e9 r\u00e9partis en cinq domaines-clef, dans le cadre desquels le Secr\u00e9tariat a d\u2019abord pr\u00e9sent\u00e9 une synth\u00e8se de la situation actuelle et les principales t\u00e2ches, suite \u00e0 quoi, des repr\u00e9sentants de <em>DG MOVE, CINEA, EFIP,<\/em> des Etats membres de la CD et des coordinateurs\/organisateurs de divers projets ont pr\u00e9sent\u00e9 les strat\u00e9gies les plus importantes ayant trait aux ports ainsi que des informations relatives \u00e0 l\u2019activit\u00e9 portant sur des projets visant l\u2019\u00e9cologisation et la digitalisation du fonctionnement des ports.<\/p>\n<p style=\"text-align: justify;\">Il a \u00e9t\u00e9 d\u00e9cid\u00e9 que la RE PORTS devait agir en tant que plateforme d\u2019information et de communication en mati\u00e8re de strat\u00e9gies et d\u2019innovations dans l\u2019activit\u00e9 des ports. Les prochaines r\u00e9unions ont \u00e9t\u00e9 planifi\u00e9es pour le 9 mars 2022 (format en ligne) et le 29 septembre 2022 (format hybride).<\/p>\n<p><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9481 aligncenter\" src=\"https:\/\/www.danubecommission.org\/dc\/wp-content\/uploads\/2021\/10\/port_meeting.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/www.danubecommission.org\/dc\/wp-content\/uploads\/2021\/10\/port_meeting.jpg 1280w, https:\/\/www.danubecommission.org\/dc\/wp-content\/uploads\/2021\/10\/port_meeting-300x169.jpg 300w, https:\/\/www.danubecommission.org\/dc\/wp-content\/uploads\/2021\/10\/port_meeting-1024x576.jpg 1024w, https:\/\/www.danubecommission.org\/dc\/wp-content\/uploads\/2021\/10\/port_meeting-768x432.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p><strong>Pr\u00e9sentations <\/strong><\/p>\n<p><strong>Pr\u00e9sentations du Secr\u00e9tariat de la CD:<\/strong><br \/>\n<iframe style=\"width: 800px; height: 400px; border: 0;\" src=\"https:\/\/drive.google.com\/embeddedfolderview?id=1hXbnnTkRvd5dqyVnpZlz0JJaD3_97YWG#list\"><\/iframe><br \/>\n<strong>Pr\u00e9sentations de principaux intervenants :<\/strong><br \/>\n<iframe style=\"width: 800px; height: 700px; border: 0;\" src=\"https:\/\/drive.google.com\/embeddedfolderview?id=1y-cH86kFkQ8UrJ025kU_a9-lCs8jFcuN#list\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Le 30 septembre 2021, la Commission du Danube (CD) a organis\u00e9 une premi\u00e8re r\u00e9union\u00a0 d\u2019experts pour le d\u00e9veloppement des<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[274],"tags":[],"class_list":["post-9475","post","type-post","status-publish","format-standard","hentry","category-evenements"],"_links":{"self":[{"href":"https:\/\/www.danubecommission.org\/dc\/wp-json\/wp\/v2\/posts\/9475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.danubecommission.org\/dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.danubecommission.org\/dc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.danubecommission.org\/dc\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.danubecommission.org\/dc\/wp-json\/wp\/v2\/comments?post=9475"}],"version-history":[{"count":0,"href":"https:\/\/www.danubecommission.org\/dc\/wp-json\/wp\/v2\/posts\/9475\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.danubecommission.org\/dc\/wp-json\/wp\/v2\/media?parent=9475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.danubecommission.org\/dc\/wp-json\/wp\/v2\/categories?post=9475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.danubecommission.org\/dc\/wp-json\/wp\/v2\/tags?post=9475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}